
{"id":22485,"date":"2023-08-25T14:56:53","date_gmt":"2023-08-25T06:56:53","guid":{"rendered":"http:\/\/ntp.global-jt.com\/?page_id=22485"},"modified":"2024-08-13T16:01:34","modified_gmt":"2024-08-13T08:01:34","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/en.debaochina.com\/turkish\/contact-us","title":{"rendered":"Bize Ula\u015f\u0131n"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"22485\" class=\"elementor elementor-22485\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e446a0 elementor-section-stretched scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"9e446a0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b30089 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"0b30089\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af07d47 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"af07d47\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6db3ff9 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"6db3ff9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-341b51e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"341b51e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7d52b5 sc_fly_static elementor-widget elementor-widget-trx_sc_icons\" data-id=\"f7d52b5\" data-element_type=\"widget\" data-widget_type=\"trx_sc_icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \tclass=\"sc_icons sc_icons_plain sc_icons_size_small sc_align_center\" ><div class=\"sc_icons_columns_wrap sc_item_columns trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\" ><div class=\"trx_addons_column-1_3\"><div class=\"sc_icons_item\"><div class=\"sc_icons_icon sc_icon_type_ icon-globe-light\" ><span class=\"sc_icon_type_ icon-globe-light\"><\/span><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><span>\u0130leti\u015fime Ge\u00e7in<\/span><\/h4><div class=\"sc_icons_item_description\"><span>E-posta: <a href=\"mailto:db@debaochina.com\">db@debaochina.com<\/a><\/span><span>Web: <a href=\"https:\/\/www.debaochina.com\">www.debaochina.com<\/a><\/span><span>Posta kodu\uff1a325409<\/span><\/div><\/div><\/div><\/div><div class=\"trx_addons_column-1_3\"><div class=\"sc_icons_item sc_icons_item_linked\"><div class=\"sc_icons_icon sc_icon_type_ icon-location-1\" ><span class=\"sc_icon_type_ icon-location-1\"><\/span><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"#map\">\r\n                                    Adres                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>Fengzhai Do\u011fal K\u00f6y\u00fc, Wandu K\u00f6y\u00fc, <\/span><span>Wanquan Kasabas\u0131, Pingyang \u0130l\u00e7esi, <\/span><span>Zhejiang, \u00c7in<\/span><\/div><a href=\"#map\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3\"><div class=\"sc_icons_item sc_icons_item_linked\"><div class=\"sc_icons_icon sc_icon_type_ icon-group-2438\" ><span class=\"sc_icon_type_ icon-group-2438\"><\/span><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"#map\">\r\n                                    Bizi Aray\u0131n                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>Telefon: <a href=\"tel:0086-13353335151\">0086-13353335151<\/a><\/span><span>Telefon: <a href=\"tel:0086-577-65578789\">0086-577-65578789<\/a><\/span><span>Telefon: <a href=\"tel:0086-577-65668588\">0086-577-65568588<\/a><\/span><\/div><a href=\"#map\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><\/div><\/div><!-- \/.sc_icons -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f015566 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"f015566\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1d3907 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"c1d3907\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1808b8 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f1808b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0230813 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"0230813\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">Sorular\u0131n\u0131z m\u0131 var?<\/span><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Bize Ula\u015f\u0131n<\/span><\/h1><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69aa6dd sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"69aa6dd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0fab0 sc_fly_static elementor-widget elementor-widget-trx_sc_contact_form_7\" data-id=\"4e0fab0\" data-element_type=\"widget\" data-widget_type=\"trx_sc_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/turkish\/wp-json\/wp\/v2\/pages\/22485#wpcf7-f5-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/turkish\/wp-json\/wp\/v2\/pages\/22485#wpcf7-f5-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"form-style-1\">\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-name\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0130sim\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-email\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-posta Adresi\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-phone\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefon\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-subject\"><span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Konu\" value=\"\" type=\"text\" name=\"subject\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_3\">\n\t\t\t<p><span class=\"style-line\"><span class=\"wpcf7-form-control-wrap country_auto your-country\"><select class=\"wpcf7-form-control wpcf7-country_auto wpcf7-validates-as-required wpcf7-select country_auto\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-country\" ><option value=\"0\">\u00dclke Se\u00e7iniz<\/option><option value='Afghanistan' data-id='1'>Afganistan<\/option><option value='Aland Islands' data-id='2'>Aland Adalar\u0131<\/option><option value='Albania' data-id='3'>Arnavutluk<\/option><option value='Algeria' data-id='4'>Cezayir<\/option><option value='American Samoa' data-id='5'>Amerikan Samoas\u0131<\/option><option value='Andorra' data-id='6'>Andorra<\/option><option value='Angola' data-id='7'>Angola<\/option><option value='Anguilla' data-id='8'>Anguilla<\/option><option value='Antarctica' data-id='9'>Antarktika<\/option><option value='Antigua And Barbuda' data-id='10'>Antigua ve Barbuda<\/option><option value='Argentina' data-id='11'>Arjantin<\/option><option value='Armenia' data-id='12'>Ermenistan<\/option><option value='Aruba' data-id='13'>Aruba<\/option><option value='Australia' data-id='14'>Avustralya<\/option><option value='Austria' data-id='15'>Avusturya<\/option><option value='Azerbaijan' data-id='16'>Azerbaycan<\/option><option value='Bahamas The' data-id='17'>Bahamalar<\/option><option value='Bahrain' data-id='18'>Bahreyn<\/option><option value='Bangladesh' data-id='19'>Banglade\u015f<\/option><option value='Barbados' data-id='20'>Barbados<\/option><option value='Belarus' data-id='21'>Belarus<\/option><option value='Belgium' data-id='22'>Bel\u00e7ika<\/option><option value='Belize' data-id='23'>Belize<\/option><option value='Benin' data-id='24'>Benin<\/option><option value='Bermuda' data-id='25'>Bermuda<\/option><option value='Bhutan' data-id='26'>Bhutan<\/option><option value='Bolivia' data-id='27'>Bolivya<\/option><option value='Bosnia and Herzegovina' data-id='28'>Bosna Hersek<\/option><option value='Botswana' data-id='29'>Botsvana<\/option><option value='Bouvet Island' data-id='30'>Bouvet Adas\u0131<\/option><option value='Brazil' data-id='31'>Brezilya<\/option><option value='British Indian Ocean Territory' data-id='32'>Britanya Hint Okyanusu Topraklar\u0131<\/option><option value='Brunei' data-id='33'>Brunei<\/option><option value='Bulgaria' data-id='34'>Bulgaristan<\/option><option value='Burkina Faso' data-id='35'>Burkina Faso<\/option><option value='Burundi' data-id='36'>Burundi<\/option><option value='Cambodia' data-id='37'>Kambo\u00e7ya<\/option><option value='Cameroon' data-id='38'>Kamerun<\/option><option value='Canada' data-id='39'>Kanada<\/option><option value='Cape Verde' data-id='40'>Ye\u015fil Burun Adalar\u0131<\/option><option value='Cayman Islands' data-id='41'>Cayman Adalar\u0131<\/option><option value='Central African Republic' data-id='42'>Orta Afrika Cumhuriyeti<\/option><option value='Chad' data-id='43'>Chad<\/option><option value='Chile' data-id='44'>\u015eili<\/option><option value='China' data-id='45'>\u00c7in<\/option><option value='Christmas Island' data-id='46'>Noel Adas\u0131<\/option><option value='Cocos (Keeling) Islands' data-id='47'>Cocos (Keeling) Adalar\u0131<\/option><option value='Colombia' data-id='48'>Kolombiya<\/option><option value='Comoros' data-id='49'>Komorlar<\/option><option value='Congo' data-id='50'>Kongo<\/option><option value='Congo The Democratic Republic Of The' data-id='51'>Kongo Demokratik Cumhuriyeti<\/option><option value='Cook Islands' data-id='52'>Cook Adalar\u0131<\/option><option value='Costa Rica' data-id='53'>Kosta Rika<\/option><option value='Cote D&#039;Ivoire (Ivory Coast)' data-id='54'>Cote D&#039;Ivoire (Fildi\u015fi Sahili)<\/option><option value='Croatia (Hrvatska)' data-id='55'>H\u0131rvatistan (Hrvatska)<\/option><option value='Cuba' data-id='56'>K\u00fcba<\/option><option value='Cyprus' data-id='57'>K\u0131br\u0131s<\/option><option value='Czech Republic' data-id='58'>\u00c7ek Cumhuriyeti<\/option><option value='Denmark' data-id='59'>Danimarka<\/option><option value='Djibouti' data-id='60'>Cibuti<\/option><option value='Dominica' data-id='61'>Dominika<\/option><option value='Dominican Republic' data-id='62'>Dominik Cumhuriyeti<\/option><option value='East Timor' data-id='63'>Do\u011fu Timor<\/option><option value='Ecuador' data-id='64'>Ekvador<\/option><option value='Egypt' data-id='65'>M\u0131s\u0131r<\/option><option value='El Salvador' data-id='66'>El Salvador<\/option><option value='Equatorial Guinea' data-id='67'>Ekvator Ginesi<\/option><option value='Eritrea' data-id='68'>Eritre<\/option><option value='Estonia' data-id='69'>Estonya<\/option><option value='Ethiopia' data-id='70'>Etiyopya<\/option><option value='Falkland Islands' data-id='71'>Falkland Adalar\u0131<\/option><option value='Faroe Islands' data-id='72'>Faroe Adalar\u0131<\/option><option value='Fiji Islands' data-id='73'>Fiji Adalar\u0131<\/option><option value='Finland' data-id='74'>Finlandiya<\/option><option value='France' data-id='75'>Fransa<\/option><option value='French Guiana' data-id='76'>Frans\u0131z Guyanas\u0131<\/option><option value='French Polynesia' data-id='77'>Frans\u0131z Polinezyas\u0131<\/option><option value='French Southern Territories' data-id='78'>Frans\u0131z G\u00fcney Topraklar\u0131<\/option><option value='Gabon' data-id='79'>Gabon<\/option><option value='Gambia The' data-id='80'>Gambiya<\/option><option value='Georgia' data-id='81'>G\u00fcrcistan<\/option><option value='Germany' data-id='82'>Almanya<\/option><option value='Ghana' data-id='83'>Gana<\/option><option value='Gibraltar' data-id='84'>Cebelitar\u0131k<\/option><option value='Greece' data-id='85'>Yunanistan<\/option><option value='Greenland' data-id='86'>Gr\u00f6nland<\/option><option value='Grenada' data-id='87'>Grenada<\/option><option value='Guadeloupe' data-id='88'>Guadeloupe<\/option><option value='Guam' data-id='89'>Guam<\/option><option value='Guatemala' data-id='90'>Guatemala<\/option><option value='Guernsey and Alderney' data-id='91'>Guernsey ve Alderney<\/option><option value='Guinea' data-id='92'>Gine<\/option><option value='Guinea-Bissau' data-id='93'>Gine-Bissau<\/option><option value='Guyana' data-id='94'>Guyana<\/option><option value='Haiti' data-id='95'>Haiti<\/option><option value='Heard and McDonald Islands' data-id='96'>Heard ve McDonald Adalar\u0131<\/option><option value='Honduras' data-id='97'>Honduras<\/option><option value='Hong Kong S.A.R.' data-id='98'>Hong Kong S.A.R.<\/option><option value='Hungary' data-id='99'>Macaristan<\/option><option value='Iceland' data-id='100'>\u0130zlanda<\/option><option value='India' data-id='101'>Hindistan<\/option><option value='Indonesia' data-id='102'>Endonezya<\/option><option value='Iran' data-id='103'>\u0130ran<\/option><option value='Iraq' data-id='104'>Irak<\/option><option value='Ireland' data-id='105'>\u0130rlanda<\/option><option value='Israel' data-id='106'>\u0130srail<\/option><option value='Italy' data-id='107'>\u0130talya<\/option><option value='Jamaica' data-id='108'>Jamaika<\/option><option value='Japan' data-id='109'>Japonya<\/option><option value='Jersey' data-id='110'>Jersey<\/option><option value='Jordan' data-id='111'>\u00dcrd\u00fcn<\/option><option value='Kazakhstan' data-id='112'>Kazakistan<\/option><option value='Kenya' data-id='113'>Kenya<\/option><option value='Kiribati' data-id='114'>Kiribati<\/option><option value='Korea North' data-id='115'>Kuzey Kore<\/option><option value='Korea South' data-id='116'>G\u00fcney Kore<\/option><option value='Kuwait' data-id='117'>Kuveyt<\/option><option value='Kyrgyzstan' data-id='118'>K\u0131rg\u0131zistan<\/option><option value='Laos' data-id='119'>Laos<\/option><option value='Latvia' data-id='120'>Letonya<\/option><option value='Lebanon' data-id='121'>L\u00fcbnan<\/option><option value='Lesotho' data-id='122'>Lesotho<\/option><option value='Liberia' data-id='123'>Liberya<\/option><option value='Libya' data-id='124'>Libya<\/option><option value='Liechtenstein' data-id='125'>Lihten\u015ftayn<\/option><option value='Lithuania' data-id='126'>Litvanya<\/option><option value='Luxembourg' data-id='127'>L\u00fcksemburg<\/option><option value='Macau S.A.R.' data-id='128'>Macau S.A.R.<\/option><option value='Macedonia' data-id='129'>Makedonya<\/option><option value='Madagascar' data-id='130'>Madagaskar<\/option><option value='Malawi' data-id='131'>Malavi<\/option><option value='Malaysia' data-id='132'>Malezya<\/option><option value='Maldives' data-id='133'>Maldivler<\/option><option value='Mali' data-id='134'>Mali<\/option><option value='Malta' data-id='135'>Malta<\/option><option value='Man (Isle of)' data-id='136'>Man (Isle of)<\/option><option value='Marshall Islands' data-id='137'>Marshall Adalar\u0131<\/option><option value='Martinique' data-id='138'>Martinique<\/option><option value='Mauritania' data-id='139'>Moritanya<\/option><option value='Mauritius' data-id='140'>Mauritius<\/option><option value='Mayotte' data-id='141'>Mayotte<\/option><option value='Mexico' data-id='142'>Meksika<\/option><option value='Micronesia' data-id='143'>Mikronezya<\/option><option value='Moldova' data-id='144'>Moldova<\/option><option value='Monaco' data-id='145'>Monako<\/option><option value='Mongolia' data-id='146'>Mo\u011folistan<\/option><option value='Montenegro' data-id='147'>Karada\u011f<\/option><option value='Montserrat' data-id='148'>Montserrat<\/option><option value='Morocco' data-id='149'>Fas<\/option><option value='Mozambique' data-id='150'>Mozambik<\/option><option value='Myanmar' data-id='151'>Myanmar<\/option><option value='Namibia' data-id='152'>Namibya<\/option><option value='Nauru' data-id='153'>Nauru<\/option><option value='Nepal' data-id='154'>Nepal<\/option><option value='Netherlands Antilles' data-id='155'>Hollanda Antilleri<\/option><option value='Netherlands The' data-id='156'>Hollanda<\/option><option value='New Caledonia' data-id='157'>Yeni Kaledonya<\/option><option value='New Zealand' data-id='158'>Yeni Zelanda<\/option><option value='Nicaragua' data-id='159'>Nikaragua<\/option><option value='Niger' data-id='160'>Nijer<\/option><option value='Nigeria' data-id='161'>Nijerya<\/option><option value='Niue' data-id='162'>Niue<\/option><option value='Norfolk Island' data-id='163'>Norfolk Adas\u0131<\/option><option value='Northern Mariana Islands' data-id='164'>Kuzey Mariana Adalar\u0131<\/option><option value='Norway' data-id='165'>Norve\u00e7<\/option><option value='Oman' data-id='166'>Umman<\/option><option value='Pakistan' data-id='167'>Pakistan<\/option><option value='Palau' data-id='168'>Palau<\/option><option value='Palestinian Territory Occupied' data-id='169'>\u0130\u015fgal Edilen Filistin Topraklar\u0131<\/option><option value='Panama' data-id='170'>Panama<\/option><option value='Papua new Guinea' data-id='171'>Papua Yeni Gine<\/option><option value='Paraguay' data-id='172'>Paraguay<\/option><option value='Peru' data-id='173'>Peru<\/option><option value='Philippines' data-id='174'>Filipinler<\/option><option value='Pitcairn Island' data-id='175'>Pitcairn Adas\u0131<\/option><option value='Poland' data-id='176'>Polonya<\/option><option value='Portugal' data-id='177'>Portekiz<\/option><option value='Puerto Rico' data-id='178'>Porto Riko<\/option><option value='Qatar' data-id='179'>Katar<\/option><option value='Reunion' data-id='180'>Yeniden Birle\u015fme<\/option><option value='Romania' data-id='181'>Romanya<\/option><option value='Russia' data-id='182'>Rusya<\/option><option value='Rwanda' data-id='183'>Ruanda<\/option><option value='Saint Helena' data-id='184'>Saint Helena<\/option><option value='Saint Kitts And Nevis' data-id='185'>Saint Kitts ve Nevis<\/option><option value='Saint Lucia' data-id='186'>Saint Lucia<\/option><option value='Saint Pierre and Miquelon' data-id='187'>Saint Pierre ve Miquelon<\/option><option value='Saint Vincent And The Grenadines' data-id='188'>Saint Vincent ve Grenadinler<\/option><option value='Saint-Barthelemy' data-id='189'>Saint-Barthelemy<\/option><option value='Saint-Martin (French part)' data-id='190'>Saint-Martin (Frans\u0131z b\u00f6lgesi)<\/option><option value='Samoa' data-id='191'>Samoa<\/option><option value='San Marino' data-id='192'>San Marino<\/option><option value='Sao Tome and Principe' data-id='193'>Sao Tome ve Principe<\/option><option value='Saudi Arabia' data-id='194'>Suudi Arabistan<\/option><option value='Senegal' data-id='195'>Senegal<\/option><option value='Serbia' data-id='196'>S\u0131rbistan<\/option><option value='Seychelles' data-id='197'>Sey\u015feller<\/option><option value='Sierra Leone' data-id='198'>Sierra Leone<\/option><option value='Singapore' data-id='199'>Singapur<\/option><option value='Slovakia' data-id='200'>Slovakya<\/option><option value='Slovenia' data-id='201'>Slovenya<\/option><option value='Solomon Islands' data-id='202'>Solomon Adalar\u0131<\/option><option value='Somalia' data-id='203'>Somali<\/option><option value='South Africa' data-id='204'>G\u00fcney Afrika<\/option><option value='South Georgia' data-id='205'>G\u00fcney G\u00fcrcistan<\/option><option value='South Sudan' data-id='206'>G\u00fcney Sudan<\/option><option value='Spain' data-id='207'>\u0130spanya<\/option><option value='Sri Lanka' data-id='208'>Sri Lanka<\/option><option value='Sudan' data-id='209'>Sudan<\/option><option value='Suriname' data-id='210'>Surinam<\/option><option value='Svalbard And Jan Mayen Islands' data-id='211'>Svalbard ve Jan Mayen Adalar\u0131<\/option><option value='Swaziland' data-id='212'>Svaziland<\/option><option value='Sweden' data-id='213'>\u0130sve\u00e7<\/option><option value='Switzerland' data-id='214'>\u0130svi\u00e7re<\/option><option value='Syria' data-id='215'>Suriye<\/option><option value='Taiwan' data-id='216'>Tayvan<\/option><option value='Tajikistan' data-id='217'>Tacikistan<\/option><option value='Tanzania' data-id='218'>Tanzanya<\/option><option value='Thailand' data-id='219'>Tayland<\/option><option value='Togo' data-id='220'>Togo<\/option><option value='Tokelau' data-id='221'>Tokelau<\/option><option value='Tonga' data-id='222'>Tonga<\/option><option value='Trinidad And Tobago' data-id='223'>Trinidad ve Tobago<\/option><option value='Tunisia' data-id='224'>Tunus<\/option><option value='Turkey' data-id='225'>T\u00fcrkiye<\/option><option value='Turkmenistan' data-id='226'>T\u00fcrkmenistan<\/option><option value='Turks And Caicos Islands' data-id='227'>Turks ve Caicos Adalar\u0131<\/option><option value='Tuvalu' data-id='228'>Tuvalu<\/option><option value='Uganda' data-id='229'>Uganda<\/option><option value='Ukraine' data-id='230'>Ukrayna<\/option><option value='United Arab Emirates' data-id='231'>Birle\u015fik Arap Emirlikleri<\/option><option value='United Kingdom' data-id='232'>Birle\u015fik Krall\u0131k<\/option><option value='United States' data-id='233'>Birle\u015fik Devletler<\/option><option value='United States Minor Outlying Islands' data-id='234'>Amerika Birle\u015fik Devletleri K\u00fc\u00e7\u00fck D\u0131\u015f Adalar\u0131<\/option><option value='Uruguay' data-id='235'>Uruguay<\/option><option value='Uzbekistan' data-id='236'>\u00d6zbekistan<\/option><option value='Vanuatu' data-id='237'>Vanuatu<\/option><option value='Vatican City State (Holy See)' data-id='238'>Vatikan \u015eehir Devleti (Holy See)<\/option><option value='Venezuela' data-id='239'>Venezuela<\/option><option value='Vietnam' data-id='240'>Vietnam<\/option><option value='Virgin Islands (British)' data-id='241'>Virgin Adalar\u0131 (\u0130ngiliz)<\/option><option value='Virgin Islands (US)' data-id='242'>Virgin Adalar\u0131 (ABD)<\/option><option value='Wallis And Futuna Islands' data-id='243'>Wallis ve Futuna Adalar\u0131<\/option><option value='Western Sahara' data-id='244'>Bat\u0131 Sahra<\/option><option value='Yemen' data-id='245'>Yemen<\/option><option value='Zambia' data-id='246'>Zambiya<\/option><option value='Zimbabwe' data-id='247'>Zimbabve<\/option><\/select><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_3\">\n\t\t\t<p><span class=\"style-line\"><span class=\"wpcf7-form-control-wrap state_auto your-state\"><select class=\"wpcf7-form-control wpcf7-state_auto wpcf7-validates-as-required wpcf7-select state_auto\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-state\" ><option value=\"0\">Eyalet Se\u00e7iniz<\/option><\/select><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_3\">\n\t\t\t<p><span class=\"style-line\"><span class=\"wpcf7-form-control-wrap city_auto your-city\"><select class=\"wpcf7-form-control wpcf7-city_auto wpcf7-select city_auto\" aria-invalid=\"false\" name=\"your-city\" ><option value=\"0\">\u015eehir Se\u00e7iniz<\/option><\/select><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap margin-bottom\">\n <!-- \u7559\u8a00\u5185\u5bb9\u5b57\u6bb5\uff1a\u5fc5\u987b\u6dfb\u52a0 akismet:comment_content\uff08\u6838\u5fc3\u5185\u5bb9\u8bc6\u522b\uff09 -->\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-textarea\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mesaj\" name=\"your-message\"><\/textarea><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6Lch-gUsAAAAALw0VfBSuR7r5D7LiPcNB1eqeQLn\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6Lch-gUsAAAAALw0VfBSuR7r5D7LiPcNB1eqeQLn\" frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u0130leti\u015fime Ge\u00e7in\" \/>\n\t<\/p>\n<\/div>\n<style>\n.icon-country{\nvertical-align:middle;\nmargin-right:10px;\nheight: 22px;\nwidth:22px;\n}\n<\/style><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"26\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"turkish\"\/><\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22add3f elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"22add3f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac31c56 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ac31c56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Get In Touch Email: db@debaochina.comWeb: www.debaochina.comZip code\uff1a325409 Address Fengzhai Natural Village, Wandu Village, Wanquan Town, Pingyang County, Zhejiang, China Call Us Phone: 0086-13353335151Phone: 0086-577-65578789Phone: 0086-577-65568588 Have Questions? Contact Us Select&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22485","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact Us - Zhejiang New Debao Machine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/en.debaochina.com\/turkish\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Zhejiang New Debao Machine\" \/>\n<meta property=\"og:description\" content=\"Get In Touch Email: db@debaochina.comWeb: www.debaochina.comZip code\uff1a325409 Address Fengzhai Natural Village, Wandu Village, Wanquan Town, Pingyang County, Zhejiang, China Call Us Phone: 0086-13353335151Phone: 0086-577-65578789Phone: 0086-577-65568588 Have Questions? Contact Us Select&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/en.debaochina.com\/turkish\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Zhejiang New Debao Machine\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-13T08:01:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/en.debaochina.com\/contact-us\",\"url\":\"https:\/\/en.debaochina.com\/contact-us\",\"name\":\"Contact Us - Zhejiang New Debao Machine\",\"isPartOf\":{\"@id\":\"https:\/\/en.debaochina.com\/#website\"},\"datePublished\":\"2023-08-25T06:56:53+00:00\",\"dateModified\":\"2024-08-13T08:01:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/en.debaochina.com\/contact-us#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/en.debaochina.com\/contact-us\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/en.debaochina.com\/contact-us#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/en.debaochina.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/en.debaochina.com\/#website\",\"url\":\"https:\/\/en.debaochina.com\/\",\"name\":\"Zhejiang New Debao Machine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/en.debaochina.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/en.debaochina.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/en.debaochina.com\/#organization\",\"name\":\"Zhejiang New Debao Machine\",\"url\":\"https:\/\/en.debaochina.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1\",\"width\":240,\"height\":55,\"caption\":\"Zhejiang New Debao Machine\"},\"image\":{\"@id\":\"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Zhejiang New Debao Machine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/en.debaochina.com\/turkish\/contact-us\/","og_locale":"tr_TR","og_type":"article","og_title":"Contact Us - Zhejiang New Debao Machine","og_description":"Get In Touch Email: db@debaochina.comWeb: www.debaochina.comZip code\uff1a325409 Address Fengzhai Natural Village, Wandu Village, Wanquan Town, Pingyang County, Zhejiang, China Call Us Phone: 0086-13353335151Phone: 0086-577-65578789Phone: 0086-577-65568588 Have Questions? Contact Us Select&hellip;","og_url":"https:\/\/en.debaochina.com\/turkish\/contact-us\/","og_site_name":"Zhejiang New Debao Machine","article_modified_time":"2024-08-13T08:01:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/en.debaochina.com\/contact-us","url":"https:\/\/en.debaochina.com\/contact-us","name":"Contact Us - Zhejiang New Debao Machine","isPartOf":{"@id":"https:\/\/en.debaochina.com\/#website"},"datePublished":"2023-08-25T06:56:53+00:00","dateModified":"2024-08-13T08:01:34+00:00","breadcrumb":{"@id":"https:\/\/en.debaochina.com\/contact-us#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/en.debaochina.com\/contact-us"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/en.debaochina.com\/contact-us#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/en.debaochina.com\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/en.debaochina.com\/#website","url":"https:\/\/en.debaochina.com\/","name":"Zhejiang New Debao Machine","description":"","publisher":{"@id":"https:\/\/en.debaochina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/en.debaochina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/en.debaochina.com\/#organization","name":"Zhejiang New Debao Machine","url":"https:\/\/en.debaochina.com\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1","contentUrl":"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1","width":240,"height":55,"caption":"Zhejiang New Debao Machine"},"image":{"@id":"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/pages\/22485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/comments?post=22485"}],"version-history":[{"count":3,"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/pages\/22485\/revisions"}],"predecessor-version":[{"id":24562,"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/pages\/22485\/revisions\/24562"}],"wp:attachment":[{"href":"https:\/\/en.debaochina.com\/turkish\/wp-json\/wp\/v2\/media?parent=22485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}