
{"id":22416,"date":"2023-08-15T17:23:50","date_gmt":"2023-08-15T09:23:50","guid":{"rendered":"http:\/\/ntp.global-jt.com\/?page_id=22416"},"modified":"2024-03-12T10:37:54","modified_gmt":"2024-03-12T02:37:54","slug":"packaging-solution","status":"publish","type":"page","link":"https:\/\/en.debaochina.com\/portuguese\/solutions\/packaging-solution","title":{"rendered":"Solu\u00e7\u00e3o de embalagem"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"22416\" class=\"elementor elementor-22416\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-043a925 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"043a925\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-495fd3e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"495fd3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d4240c sc_height_large sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2d4240c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b39cb5a sc_layouts_hide_on_notebook sc_layouts_hide_on_tablet sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"b39cb5a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e02254f sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"e02254f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">solu\u00e7\u00e3o online para m\u00e1quina de x\u00edcaras<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dda3d51 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"dda3d51\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97b2135 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"97b2135\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b87693 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"0b87693\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e16b91a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e16b91a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bee82e elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"9bee82e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d142c4 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"5d142c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa1e34d elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"aa1e34d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b720108 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b720108\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b75588 minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"5b75588\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-258S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83ba18d elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"83ba18d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23872\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9d6a3e8 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9d6a3e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d6dc4 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"38d6dc4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6bf1c99 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"6bf1c99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b68f5fc minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"b68f5fc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD110<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed7bb86 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"ed7bb86\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23917\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99e2bc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"99e2bc1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6838cdd sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"6838cdd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a69488a solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"a69488a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48b8130 sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"48b8130\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18ec77e sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"18ec77e\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db801b1 solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"db801b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de2d1c3 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"de2d1c3\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7babb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"a7babb2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceaeabe sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ceaeabe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-747596b sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"747596b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efe2b6a elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"efe2b6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cafc0d6 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"cafc0d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0c68d0 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"a0c68d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc904f2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fc904f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e308b77 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e308b77\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cd0029a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"cd0029a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7414b2b minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"7414b2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-138S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ec151 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"31ec151\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23876\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e787bb4 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e787bb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac7948f sc_fly_static elementor-widget elementor-widget-image\" data-id=\"ac7948f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bd3895e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"bd3895e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57346c8 minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"57346c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD110<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fcce7c sc_fly_static elementor-widget elementor-widget-image\" data-id=\"0fcce7c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23917\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-636fb39 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"636fb39\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8832783 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8832783\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3bde43a solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3bde43a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db53fcd sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"db53fcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7e13b sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"3d7e13b\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-80c040c solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"80c040c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-560327d sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"560327d\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25a62db elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"25a62db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89e1608 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"89e1608\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f4b39 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"64f4b39\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e2d0e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"6e2d0e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2437deb sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"2437deb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4e3b93 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"d4e3b93\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e6ffc22 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e6ffc22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7331028 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7331028\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8c26c23 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8c26c23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a1bc9c minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"1a1bc9c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-1250S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d3c7f1 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"1d3c7f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23890\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-1250S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7df8245 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7df8245\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-312b126 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"312b126\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b56b21f sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b56b21f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1f63aa minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"d1f63aa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD150<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cccdc5 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"4cccdc5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23917\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06dab20 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"06dab20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a10d3c4 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a10d3c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-527e89e solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"527e89e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3661ff8 sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3661ff8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-352e44a sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"352e44a\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f021a1e solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f021a1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18fd97b sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"18fd97b\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bd5a55 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"4bd5a55\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a3d4f0 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7a3d4f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e36b63a sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e36b63a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-daa91ca elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"daa91ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5297ab2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"5297ab2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56201fb elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"56201fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8011c30 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8011c30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62c1756 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"62c1756\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a80e5a9 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a80e5a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e1f2f minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"b4e1f2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-5000S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aff8716 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"aff8716\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23920\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-5000S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-36e4e05 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"36e4e05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a3a570 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"1a3a570\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-24c9021 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"24c9021\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c2b9a0 minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"3c2b9a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD200<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55110e9 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"55110e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23921\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DXD200.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3b8879 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"b3b8879\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-401e0a9 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"401e0a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eba73e3 solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"eba73e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbcffea sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fbcffea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71a684c sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"71a684c\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce2aae8 solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ce2aae8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-905a925 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"905a925\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cca2f41 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"cca2f41\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43ece9a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"43ece9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c624069 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c624069\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-770e1ad elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"770e1ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3738665 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3738665\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b3e3a3 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"5b3e3a3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-501b367 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"501b367\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca7fa78 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ca7fa78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f3b864d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f3b864d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43a9e6f minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"43a9e6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-258S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-852ae86 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"852ae86\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23872\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-258S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-fd81e13 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fd81e13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95e9bd0 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"95e9bd0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4b3a29c sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4b3a29c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7022943 minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"7022943\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD110<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2056043 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"2056043\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23917\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e227844 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e227844\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf23d3b sc_fly_static elementor-widget elementor-widget-image\" data-id=\"bf23d3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9d4ef38 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9d4ef38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d61961e minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"d61961e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DK500<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6404fc5 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"6404fc5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23926\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fc99ea elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3fc99ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-669a7b4 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"669a7b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-323050d solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"323050d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d44b89 sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1d44b89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3025b63 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"3025b63\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3022da3 solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3022da3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23e3fe4 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"23e3fe4\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bee9ea6 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"bee9ea6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-006d047 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"006d047\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f272409 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"f272409\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51a6c92 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"51a6c92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bc275f0 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"bc275f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0a3407 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"d0a3407\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"676\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?fit=600%2C676&amp;ssl=1\" class=\"attachment-large size-large wp-image-23918\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=370%2C417&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg?resize=410%2C462&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-86292bd sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"86292bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c989353 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"c989353\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2b9aeac sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"2b9aeac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-861628c minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"861628c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-138S<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5af1fde elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"5af1fde\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23876\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-138S.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4bc13b2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4bc13b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-709812c sc_fly_static elementor-widget elementor-widget-image\" data-id=\"709812c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-fff83d8 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fff83d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20e98b5 minword elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"20e98b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DXD110<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-365497d elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-image\" data-id=\"365497d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23917\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Sleeve-NEWTOP-DXD110.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-db479f9 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"db479f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd39364 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"cd39364\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?fit=512%2C512&amp;ssl=1\" class=\"attachment-large size-large wp-image-24056\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=370%2C370&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=120%2C120&amp;ssl=1 120w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2024\/02\/plus.png?resize=410%2C410&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-97ebf10 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"97ebf10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0249ccb minword sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"0249ccb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-small\">NEWTOP-DK500<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ce7637 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"2ce7637\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"407\" src=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?fit=600%2C407&amp;ssl=1\" class=\"attachment-large size-large wp-image-23926\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=150%2C102&amp;ssl=1 150w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=370%2C251&amp;ssl=1 370w, https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-NEWTOP-DK500.jpg?resize=410%2C278&amp;ssl=1 410w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5a0444 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e5a0444\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbbee02 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fbbee02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b3626a solution-button elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"4b3626a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a1b9ec2 sc-mobile_content_align_inherit solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a1b9ec2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa82048 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"aa82048\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"#\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_with_icon sc_button_icon_right\" ><span class=\"sc_button_icon\"><span class=\"icon-play-big\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">V\u00eddeo<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a427615 solution-button-one sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a427615\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c90d0c sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"6c90d0c\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/en.debaochina.com\/portuguese\/contact-us\/\" class=\"sc_button sc_button_default sc_button_size_normal sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Contate-nos<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3eb86ab elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3eb86ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-063afda sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"063afda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b72fa11 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"b72fa11\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac27097 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ac27097\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d8f213 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9d8f213\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39ec401 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"39ec401\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48d39fd sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"48d39fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-986b59d sc_height_large sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"986b59d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee6cb7 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"6ee6cb7\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">Melhor escolha<\/span><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Categorias de produtos<\/span><\/h1><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e2a97d sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"1e2a97d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7534de0 sy-cpfl sc_fly_static elementor-widget elementor-widget-trx_sc_icons\" data-id=\"7534de0\" data-element_type=\"widget\" data-widget_type=\"trx_sc_icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \tclass=\"sc_icons sc_icons_accent2 sc_icons_size_medium sc_align_left\" ><div class=\"sc_icons_columns_wrap sc_item_columns trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\" ><div class=\"trx_addons_column-1_5\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_image\" ><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ntp.global-jt.com\/wp-content\/uploads\/2023\/08\/fenlei5.png?w=1290\" alt=\"Icon\" data-recalc-dims=\"1\"><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-cup-machine\/\">\r\n                                    M\u00e1quina de Copos de Papel                                    <\/a><\/h4><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-cup-machine\/\" class=\"sc_icons_item_more_link\">\r\n                        <span class=\"link_text\">Read more<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-cup-machine\/\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_5\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_image\" ><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ntp.global-jt.com\/wp-content\/uploads\/2023\/08\/fenlei2.png?w=1290\" alt=\"Icon\" data-recalc-dims=\"1\"><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-bowl-machine\/\">\r\n                                    M\u00e1quina de Tigelas de Papel                                    <\/a><\/h4><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-bowl-machine\/\" class=\"sc_icons_item_more_link\">\r\n                        <span class=\"link_text\">Read more<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a><a href=\"https:\/\/en.debaochina.com\/portuguese\/paper-bowl-machine\/\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_5\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_image\" ><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ntp.global-jt.com\/wp-content\/uploads\/2023\/08\/fenlei1.png?w=1290\" alt=\"Icon\" data-recalc-dims=\"1\"><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/en.debaochina.com\/portuguese\/sleeve-machine\/\">\r\n                                    M\u00e1quina de mangas                                    <\/a><\/h4><a href=\"https:\/\/en.debaochina.com\/portuguese\/sleeve-machine\/\" class=\"sc_icons_item_more_link\">\r\n                        <span class=\"link_text\">Read more<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a><a href=\"https:\/\/en.debaochina.com\/portuguese\/sleeve-machine\/\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_5\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_image\" ><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ntp.global-jt.com\/wp-content\/uploads\/2023\/08\/fenlei4-1.png?w=1290\" alt=\"Icon\" data-recalc-dims=\"1\"><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/en.debaochina.com\/portuguese\/special-shaped-bowl\/\">\r\n                                    Tigela com formato especial                                    <\/a><\/h4><a href=\"https:\/\/en.debaochina.com\/portuguese\/special-shaped-bowl\/\" class=\"sc_icons_item_more_link\">\r\n                        <span class=\"link_text\">Read more<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a><a href=\"https:\/\/en.debaochina.com\/portuguese\/special-shaped-bowl\/\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_5\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_image\" ><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ntp.global-jt.com\/wp-content\/uploads\/2023\/08\/fenlei3.png?w=1290\" alt=\"Icon\" data-recalc-dims=\"1\"><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/en.debaochina.com\/portuguese\/ancillary-equipments\/\">\r\n                                    Equipamentos auxiliares                                    <\/a><\/h4><a href=\"https:\/\/en.debaochina.com\/portuguese\/ancillary-equipments\/\" class=\"sc_icons_item_more_link\">\r\n                        <span class=\"link_text\">Read more<\/span><span class=\"link_icon\"><\/span>\r\n                        <\/a><a href=\"https:\/\/en.debaochina.com\/portuguese\/ancillary-equipments\/\"\r\n                        class=\"sc_icons_item_link\">\r\n                        <\/a><\/div><\/div><\/div><\/div><\/div><!-- \/.sc_icons -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cup machine online solution NEWTOP-258S NEWTOP-DXD110 Video Contact Us NEWTOP-138S NEWTOP-DXD110 Video Contact Us NEWTOP-1250S NEWTOP-DXD150 Video Contact Us NEWTOP-5000S NEWTOP-DXD200 Video Contact Us NEWTOP-258S NEWTOP-DXD110 NEWTOP-DK500 Video Contact Us&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":22414,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22416","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Packaging solution - Zhejiang New Debao Machine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/en.debaochina.com\/portuguese\/solutions\/packaging-solution\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Packaging solution - Zhejiang New Debao Machine\" \/>\n<meta property=\"og:description\" content=\"Cup machine online solution NEWTOP-258S NEWTOP-DXD110 Video Contact Us NEWTOP-138S NEWTOP-DXD110 Video Contact Us NEWTOP-1250S NEWTOP-DXD150 Video Contact Us NEWTOP-5000S NEWTOP-DXD200 Video Contact Us NEWTOP-258S NEWTOP-DXD110 NEWTOP-DK500 Video Contact Us&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/en.debaochina.com\/portuguese\/solutions\/packaging-solution\/\" \/>\n<meta property=\"og:site_name\" content=\"Zhejiang New Debao Machine\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T02:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution\",\"url\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution\",\"name\":\"Packaging solution - Zhejiang New Debao Machine\",\"isPartOf\":{\"@id\":\"https:\/\/en.debaochina.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage\"},\"image\":{\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage\"},\"thumbnailUrl\":\"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg\",\"datePublished\":\"2023-08-15T09:23:50+00:00\",\"dateModified\":\"2024-03-12T02:37:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/en.debaochina.com\/solutions\/packaging-solution\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage\",\"url\":\"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg\",\"contentUrl\":\"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/en.debaochina.com\/solutions\/packaging-solution#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/en.debaochina.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions\",\"item\":\"https:\/\/en.debaochina.com\/solutions\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Packaging solution\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/en.debaochina.com\/#website\",\"url\":\"https:\/\/en.debaochina.com\/\",\"name\":\"Zhejiang New Debao Machine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/en.debaochina.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/en.debaochina.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/en.debaochina.com\/#organization\",\"name\":\"Zhejiang New Debao Machine\",\"url\":\"https:\/\/en.debaochina.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1\",\"width\":240,\"height\":55,\"caption\":\"Zhejiang New Debao Machine\"},\"image\":{\"@id\":\"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Packaging solution - Zhejiang New Debao Machine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/en.debaochina.com\/portuguese\/solutions\/packaging-solution\/","og_locale":"pt_BR","og_type":"article","og_title":"Packaging solution - Zhejiang New Debao Machine","og_description":"Cup machine online solution NEWTOP-258S NEWTOP-DXD110 Video Contact Us NEWTOP-138S NEWTOP-DXD110 Video Contact Us NEWTOP-1250S NEWTOP-DXD150 Video Contact Us NEWTOP-5000S NEWTOP-DXD200 Video Contact Us NEWTOP-258S NEWTOP-DXD110 NEWTOP-DK500 Video Contact Us&hellip;","og_url":"https:\/\/en.debaochina.com\/portuguese\/solutions\/packaging-solution\/","og_site_name":"Zhejiang New Debao Machine","article_modified_time":"2024-03-12T02:37:54+00:00","og_image":[{"url":"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution","url":"https:\/\/en.debaochina.com\/solutions\/packaging-solution","name":"Packaging solution - Zhejiang New Debao Machine","isPartOf":{"@id":"https:\/\/en.debaochina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage"},"image":{"@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage"},"thumbnailUrl":"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg","datePublished":"2023-08-15T09:23:50+00:00","dateModified":"2024-03-12T02:37:54+00:00","breadcrumb":{"@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/en.debaochina.com\/solutions\/packaging-solution"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution#primaryimage","url":"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg","contentUrl":"https:\/\/en.debaochina.com\/wp-content\/uploads\/2023\/12\/Packaging-sample-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/en.debaochina.com\/solutions\/packaging-solution#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/en.debaochina.com\/"},{"@type":"ListItem","position":2,"name":"Solutions","item":"https:\/\/en.debaochina.com\/solutions"},{"@type":"ListItem","position":3,"name":"Packaging solution"}]},{"@type":"WebSite","@id":"https:\/\/en.debaochina.com\/#website","url":"https:\/\/en.debaochina.com\/","name":"Zhejiang New Debao Machine","description":"","publisher":{"@id":"https:\/\/en.debaochina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/en.debaochina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/en.debaochina.com\/#organization","name":"Zhejiang New Debao Machine","url":"https:\/\/en.debaochina.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1","contentUrl":"https:\/\/i0.wp.com\/en.debaochina.com\/wp-content\/uploads\/2023\/04\/logo-1.png?fit=240%2C55&ssl=1","width":240,"height":55,"caption":"Zhejiang New Debao Machine"},"image":{"@id":"https:\/\/en.debaochina.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/pages\/22416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/comments?post=22416"}],"version-history":[{"count":0,"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/pages\/22416\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/pages\/22414"}],"wp:attachment":[{"href":"https:\/\/en.debaochina.com\/portuguese\/wp-json\/wp\/v2\/media?parent=22416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}